{"id":1846,"count":1,"description":"","link":"https:\/\/henningbochert.de\/en\/tag\/friederike\/","name":"friederike","slug":"friederike","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/henningbochert.de\/en\/wp-json\/wp\/v2\/tags\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/henningbochert.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/henningbochert.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/henningbochert.de\/en\/wp-json\/wp\/v2\/posts?tags=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}